{"id":2935,"date":"2015-07-30T13:23:31","date_gmt":"2015-07-30T12:23:31","guid":{"rendered":"http:\/\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg"},"modified":"2015-07-30T13:23:31","modified_gmt":"2015-07-30T12:23:31","slug":"bretagne_2015-12","status":"inherit","type":"attachment","link":"https:\/\/sven-teuber.info\/wordpress\/photos-bretagne\/bretagne_2015-12\/","title":{"rendered":"Bretagne_2015-12"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_crdt_document":""},"class_list":["post-2935","attachment","type-attachment","status-inherit","hentry"],"filename":"Bretagne_2015-12.jpg","filesize":91461,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/a3CWBT-Ll","jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?ssl=1\" rel=\"lightbox[2935]\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?fit=300%2C200&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?resize=360%2C240&amp;ssl=1 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"2935\" data-permalink=\"https:\/\/sven-teuber.info\/wordpress\/photos-bretagne\/bretagne_2015-12\/\" data-orig-file=\"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?fit=640%2C427&amp;ssl=1\" data-orig-size=\"640,427\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Copyright:Sven Teuber&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Bretagne_2015-12\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?fit=584%2C390&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":640,"height":427,"file":"2015\/07\/Bretagne_2015-12.jpg","sizes":{"thumbnail":{"file":"Bretagne_2015-12-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Bretagne_2015-12-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?fit=300%2C200&ssl=1"},"feature":{"file":"Bretagne_2015-12-360x240.jpg","width":360,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12-360x240.jpg"},"post-thumbnail":{"file":"Bretagne_2015-12-604x270.jpg","width":604,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?resize=604%2C270&ssl=1"},"full":{"file":"Bretagne_2015-12.jpg?fit=640%2C427&ssl=1","width":640,"height":427,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg?fit=640%2C427&ssl=1"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"Copyright:Sven Teuber","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":1}},"post":2936,"source_url":"https:\/\/sven-teuber.info\/wordpress\/wp-content\/uploads\/2015\/07\/Bretagne_2015-12.jpg","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Bretagne_2015-12","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/sven-teuber.info\/wordpress\/wp-json\/wp\/v2\/media\/2935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sven-teuber.info\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/sven-teuber.info\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/sven-teuber.info\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sven-teuber.info\/wordpress\/wp-json\/wp\/v2\/comments?post=2935"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2936,"href":"https:\/\/sven-teuber.info\/wordpress\/wp-json\/wp\/v2\/posts\/2936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}